
{"id":12834,"date":"2016-11-02T14:09:20","date_gmt":"2016-11-02T13:09:20","guid":{"rendered":"https:\/\/www.brickrknowledge.de\/es\/?p=12834"},"modified":"2016-11-02T14:12:55","modified_gmt":"2016-11-02T13:12:55","slug":"energia-solar-para-dummies-parte-3","status":"publish","type":"post","link":"https:\/\/brickrknowledge.eu\/es\/energia-solar-para-dummies-parte-3\/","title":{"rendered":"Energ\u00eda Solar para Dummies parte 3"},"content":{"rendered":"<p>Quienes hayan leido las entradas en mi <a href=\"https:\/\/brickrknowledge.eu\/es\/energia-solar-para-dummies-parte-1\/\">Blog \u201eEnerg\u00eda Solar para Dummies parte 1\u201c <\/a>y les haya gustado, aqu\u00ed tengo la continuaci\u00f3n. Hoy explico (una vez m\u00e1s como un principiante sangrienta en este \u00e1rea) los sistemas fotovoltaicos. Lo mejor ser\u00e1 que repitamos lo que hemos aprendido en el \u00faltimo Blog:<\/p>\n<p>Un m\u00f3dulo solar est\u00e1 compuesto por varias c\u00e9lulas solares, que conviertes la luz solar directamente en energ\u00eda el\u00e9ctrica. Existen m\u00f3dulos r\u00edgidos y m\u00f3dulos flexibles, adem\u00e1s exsisten sistemas foltovoltaicos on-grid und off-grid. Las c\u00e9lulas solares que tambi\u00e9n depende de la estructura cristalina: el Brick m\u00f3dulo solar est\u00e1 compuesto de c\u00e9lulas monocristalinas, tambi\u00e9n hay c\u00e9lulas policristalinas y amorfas. El grado de eficiencia de los m\u00f3dulos solares disminuye con el tiempo, eso depende de la degradaci\u00f3n o por ejemplo tambi\u00e9n por la contaminaci\u00f3n. Pero incluso si un m\u00f3dulo solar en alg\u00fan momento ya no funciona, puede ser reciclado hasta el 95% del mismo.<\/p>\n<p>Pero ahora algo nuevo: Nos entramos en una c\u00e9lula solar. Las c\u00e9lulas solares son piezas electr\u00f3nicas, con las que se pueden convertir energ\u00eda solar directamente en electricidad. Esto ya lo hemos entendido. \u00bfDe que est\u00e1n compuestas las c\u00e9lulas solares? La mayor\u00eda de las c\u00e9lulas solares son de silicio. El silicio es un material semiconductor que se puede obtener de toda la arena normal. Un semiconductor es en comparaci\u00f3n con un aislante, un material bajo condiciones ambientales normales (temperatura ambiental) tiene algunos electrones. Por lo tanto, en un semiconductor todav\u00eda puede fluir una peque\u00f1a cantidad de corriente, cosa que no es posible en un aislante. De ah\u00ed el nombre SEMIconductor. La corriente es, sin embargo, considerablemente m\u00e1s peque\u00f1o que en un conductor el\u00e9ctrico (por ejemplo, alambre). En pocas palabras: 1. Un conductor el\u00e9ctrico conduce la electricidad (por ejemplo, alambre, agua, carb\u00f3n, soluciones de sal, plata, oro), un semiconductor conduce energ\u00eda de forma limitada (por ejemplo, silicio) y un aislante no conduce corriente (por ejemplo, caucho, vidrio, cer\u00e1mica, \u00e1mbar, aceite).<\/p>\n<p>Con algunos trucos t\u00e9cnicos les es posible a los ingenieros aumentar especificamente la conductividad de los semiconductores. Se incorporan elementos qu\u00edmicos en el cristal de silicio, lo que conlleva que se liberan m\u00e1s electrones: Este exceso de electrones tambi\u00e9n se conoce como conductividad-n (negativo). O se introducen elementos qu\u00edmicos que producen una deficiencia de electrones en el silicio: Esto provoca que algunos lugos en el cristal de silicio no estar\u00e1n ocupados. A continuaci\u00f3n tambi\u00e9n se habla de agujeros. Estos agujeros se pueden mover ibremente, as\u00ed como los electrones. Este exceso de agujeros tambi\u00e9n se conoce como conductividad-p (positivo).<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/10\/Solar_Skizzen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12798\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/10\/Solar_Skizzen-300x212.jpg\" alt=\"Solar_Skizzen\" width=\"300\" height=\"212\" srcset=\"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen-300x212.jpg 300w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen-768x543.jpg 768w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen-1024x724.jpg 1024w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen-600x424.jpg 600w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen-453x320.jpg 453w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen-467x330.jpg 467w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En la producci\u00f3n de c\u00e9lulas solares en el cristal de silicio se produce una capa con una deficiencia de electrones y por encima una capa con exceso de electrones. Esto conlleva que en la capa fina de transici\u00f3n los electrones libres se quedan bloqueados en los agujeros (el m\u00e1s y el menos se atrae, como en los imanes). El resultado es una capa fina, denominada zona de carga espacial que no tiene ni agujeros ni electrones libres &#8211; como una capa aislante. Si posicionamos en la capa-n y en la capa-p un contacto y lo conectamos, no pasar\u00e1 nada porque est\u00e1n asilados unos de los otros. Ya que hemos aprendido que los aislantes no conducen electridiad.<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/10\/Solar_Skizzen2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12804\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/10\/Solar_Skizzen2-300x212.jpg\" alt=\"Solar_Skizzen2\" width=\"300\" height=\"212\" srcset=\"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen2-300x212.jpg 300w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen2-768x543.jpg 768w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen2-1024x724.jpg 1024w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen2-600x424.jpg 600w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen2-453x320.jpg 453w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen2-467x330.jpg 467w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Y ahora el sol entra en juego! Los rayos de sol, tal como lo vemos, est\u00e1n compuestos por part\u00edculas, conocidas como fotones. Por cierto, esta informaci\u00f3n se la debemos al famos Albert Einstein. Los rayos del sol dan ahora en la superficie de las c\u00e9lulas solares y penetran a trav\u00e9s de la fina capa-n hasta tal punto que llegan a la capa de transici\u00f3n y puede sacar a los electrones ligados en los agujeros. Es como en el juego de las canicas, cuando con tu propia canica tienes que noquear a otras de tus canicas para librar el camino. Este electrones liberados ahora fluyen a trav\u00e9s de los electrodos adyacentes de nuevo a los agujeros vac\u00edos, dando como resultado un flujo de corriente fuera de la c\u00e9lula solar. Esta corriente es entonces nuestra deseada energ\u00eda solar. Con la energ\u00eda solar podemos ponera a funcionar motores, encender bombillas, as\u00ed como recargar.<\/p>\n<p><a href=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12810\" src=\"https:\/\/www.brickrknowledge.de\/content\/uploads\/2016\/10\/Solar_Skizzen3-300x212.jpg\" alt=\"Solar_Skizzen3\" width=\"300\" height=\"212\" srcset=\"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3-300x212.jpg 300w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3-768x543.jpg 768w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3-1024x724.jpg 1024w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3-600x424.jpg 600w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3-453x320.jpg 453w, https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3-467x330.jpg 467w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Bastante complicado! Ahora incluso ya entendemos lo que ocurre realmente en el interior de las c\u00e9lulas solares. La pr\u00f3xima vez procederemos con la por ahora \u00faltima entrada en el blog sobre la energ\u00eda solar. Volveremos a repetir todo en forma corta y conoceremos las caracter\u00edsticas el\u00e9ctricas de los m\u00f3dulos solares. Entonces estaremos perfectamente preparados para los nuevas energ\u00edas renovables o una feria sobre energ\u00eda solar!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quienes hayan leido las entradas en mi Blog \u201eEnerg\u00eda Solar para Dummies parte 1\u201c y les haya gustado, aqu\u00ed tengo la continuaci\u00f3n. Hoy explico (una vez m\u00e1s como un principiante sangrienta en este \u00e1rea) los sistemas fotovoltaicos. Lo mejor ser\u00e1 que repitamos lo que hemos aprendido en el \u00faltimo Blog: Un m\u00f3dulo solar est\u00e1 compuesto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[577],"tags":[],"class_list":["post-12834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Energ\u00eda Solar para Dummies parte 3 - Brick&#039;R&#039;knowledge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energ\u00eda Solar para Dummies parte 3 - Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"og:description\" content=\"Quienes hayan leido las entradas en mi Blog \u201eEnerg\u00eda Solar para Dummies parte 1\u201c y les haya gustado, aqu\u00ed tengo la continuaci\u00f3n. Hoy explico (una vez m\u00e1s como un principiante sangrienta en este \u00e1rea) los sistemas fotovoltaicos. Lo mejor ser\u00e1 que repitamos lo que hemos aprendido en el \u00faltimo Blog: Un m\u00f3dulo solar est\u00e1 compuesto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Brick&#039;R&#039;knowledge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BrickRknowledge\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-02T13:09:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-02T13:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brickrknowledge.org\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3508\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lena Wahlsdorf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@brickrknowledge\" \/>\n<meta name=\"twitter:site\" content=\"@brickrknowledge\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lena Wahlsdorf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/\",\"url\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/\",\"name\":\"Energ\u00eda Solar para Dummies parte 3 - Brick&#039;R&#039;knowledge\",\"isPartOf\":{\"@id\":\"https:\/\/www.brickrknowledge.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg\",\"datePublished\":\"2016-11-02T13:09:20+00:00\",\"dateModified\":\"2016-11-02T13:12:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.brickrknowledge.org\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975\"},\"breadcrumb\":{\"@id\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#primaryimage\",\"url\":\"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg\",\"contentUrl\":\"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg\",\"width\":3508,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.brickrknowledge.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energ\u00eda Solar para Dummies parte 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.brickrknowledge.org\/#website\",\"url\":\"https:\/\/www.brickrknowledge.org\/\",\"name\":\"Brick&#039;R&#039;knowledge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.brickrknowledge.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.brickrknowledge.org\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975\",\"name\":\"Lena Wahlsdorf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.brickrknowledge.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g\",\"caption\":\"Lena Wahlsdorf\"},\"url\":\"https:\/\/brickrknowledge.eu\/es\/author\/lena\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energ\u00eda Solar para Dummies parte 3 - Brick&#039;R&#039;knowledge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/","og_locale":"es_ES","og_type":"article","og_title":"Energ\u00eda Solar para Dummies parte 3 - Brick&#039;R&#039;knowledge","og_description":"Quienes hayan leido las entradas en mi Blog \u201eEnerg\u00eda Solar para Dummies parte 1\u201c y les haya gustado, aqu\u00ed tengo la continuaci\u00f3n. Hoy explico (una vez m\u00e1s como un principiante sangrienta en este \u00e1rea) los sistemas fotovoltaicos. Lo mejor ser\u00e1 que repitamos lo que hemos aprendido en el \u00faltimo Blog: Un m\u00f3dulo solar est\u00e1 compuesto [&hellip;]","og_url":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/","og_site_name":"Brick&#039;R&#039;knowledge","article_publisher":"https:\/\/www.facebook.com\/BrickRknowledge","article_published_time":"2016-11-02T13:09:20+00:00","article_modified_time":"2016-11-02T13:12:55+00:00","og_image":[{"width":3508,"height":2480,"url":"https:\/\/brickrknowledge.org\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg","type":"image\/jpeg"}],"author":"Lena Wahlsdorf","twitter_card":"summary_large_image","twitter_creator":"@brickrknowledge","twitter_site":"@brickrknowledge","twitter_misc":{"Written by":"Lena Wahlsdorf","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/","url":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/","name":"Energ\u00eda Solar para Dummies parte 3 - Brick&#039;R&#039;knowledge","isPartOf":{"@id":"https:\/\/www.brickrknowledge.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#primaryimage"},"image":{"@id":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg","datePublished":"2016-11-02T13:09:20+00:00","dateModified":"2016-11-02T13:12:55+00:00","author":{"@id":"https:\/\/www.brickrknowledge.org\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975"},"breadcrumb":{"@id":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#primaryimage","url":"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg","contentUrl":"https:\/\/brickrknowledge.eu\/content\/uploads\/2016\/10\/Solar_Skizzen3.jpg","width":3508,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/brickrknowledge.org\/es\/energia-solar-para-dummies-parte-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.brickrknowledge.org\/es\/"},{"@type":"ListItem","position":2,"name":"Energ\u00eda Solar para Dummies parte 3"}]},{"@type":"WebSite","@id":"https:\/\/www.brickrknowledge.org\/#website","url":"https:\/\/www.brickrknowledge.org\/","name":"Brick&#039;R&#039;knowledge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.brickrknowledge.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.brickrknowledge.org\/#\/schema\/person\/8f69a5236cc8657e68d506287d0ae975","name":"Lena Wahlsdorf","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.brickrknowledge.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0a15594e9d4b0fc995ab2548da24d794?s=96&d=mm&r=g","caption":"Lena Wahlsdorf"},"url":"https:\/\/brickrknowledge.eu\/es\/author\/lena\/"}]}},"_links":{"self":[{"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/posts\/12834"}],"collection":[{"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/comments?post=12834"}],"version-history":[{"count":0,"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/posts\/12834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/media\/12815"}],"wp:attachment":[{"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/media?parent=12834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/categories?post=12834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brickrknowledge.eu\/es\/wp-json\/wp\/v2\/tags?post=12834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}